{"id":47,"date":"2024-09-15T16:22:32","date_gmt":"2024-09-15T19:22:32","guid":{"rendered":"http:\/\/192.168.0.52\/?p=47"},"modified":"2024-09-16T19:00:07","modified_gmt":"2024-09-16T22:00:07","slug":"f-droid","status":"publish","type":"post","link":"https:\/\/jorgecarneirob.ddns.net\/index.php\/2024\/09\/15\/f-droid\/","title":{"rendered":"F-Droid"},"content":{"rendered":"\n<p>Alternativa OpenSource ao Google PlayStore<\/p>\n\n\n\n<p><p><strong>Como funciona o F-Droid?<\/strong><\/p><\/p>\n\n\n\n<p><p>O F-Droid \u00e9 um reposit\u00f3rio de aplicativos Android de c\u00f3digo aberto. Ele funciona da seguinte forma:<br>Reposit\u00f3rio: O F-Droid mant\u00e9m um reposit\u00f3rio de aplicativos Android que s\u00e3o livres e de c\u00f3digo aberto.<br>Verifica\u00e7\u00e3o: Os aplicativos passam por um processo de verifica\u00e7\u00e3o rigoroso para garantir que sejam seguros e confi\u00e1veis.<br>Atualiza\u00e7\u00f5es: Voc\u00ea pode configurar o F-Droid para atualizar automaticamente seus aplicativos, assim como no Google Play Store.<br>Instalador: Voc\u00ea pode usar o aplicativo F-Droid para instalar, atualizar e gerenciar seus aplicativos de c\u00f3digo aberto.<br>Sem an\u00fancios ou rastreamento: Os aplicativos do F-Droid s\u00e3o livres de an\u00fancios e rastreamento.<\/p><\/p>\n\n\n\n<p><p><br><strong>Quais s\u00e3o as vantagens de usar o F-Droid?<\/strong><\/p><\/p>\n\n\n\n<p><p><span data-darkreader-inline-color=\"\" data-darkreader-inline-bgcolor=\"\" style=\"color: var(--darkreader-text--wp--preset--color--contrast, #181a1b); font-size: revert; background-color: var(--darkreader-bg--wp--preset--color--base, #dcdad7); font-family: var(--wp--preset--font-family--system-font); --darkreader-inline-color: var(--darkreader-text--darkreader-text--wp--preset--color--contrast, #2a2e2f); --darkreader-inline-bgcolor: var(--darkreader-bg--darkreader-bg--wp--preset--color--base, #c2beb9);\">Seguran\u00e7a e privacidade: Os aplicativos do F-Droid s\u00e3o verificados para garantir que sejam seguros e livres de c\u00f3digo malicioso. Al\u00e9m disso, os aplicativos n\u00e3o t\u00eam acesso a informa\u00e7\u00f5es pessoais como seus contatos ou hist\u00f3rico de navega\u00e7\u00e3o.<\/span>Controle total: Voc\u00ea tem controle total sobre os seus aplicativos. Voc\u00ea pode instalar, atualizar ou desinstalar aplicativos a qualquer momento.<br>Sem an\u00fancios: Os aplicativos do F-Droid s\u00e3o livres de an\u00fancios irritantes.<br>Sem rastreamento: Os aplicativos do F-Droid n\u00e3o rastreiam seu comportamento de uso.<br>Code aberto: Voc\u00ea pode inspecionar o c\u00f3digo-fonte dos aplicativos do F-Droid para garantir que sejam seguros e confi\u00e1veis.<br>Comunidade: O F-Droid \u00e9 uma comunidade de desenvolvedores e usu\u00e1rios que colaboram para criar e melhorar aplicativos de c\u00f3digo aberto.<\/p><br><p><strong>Instala\u00e7\u00e3o:<\/strong><\/p><br><ol><br><li>N\u00e3o \u00e9 poss\u00edvel instalar o F-Droid pela Google PlayStore, \u00e9 necess\u00e1rio acessar o site oficial <a href=\"https:\/\/f-droid.org\">https:\/\/f-droid.org<\/a> e fazer o download do .apk (arquivo de instala\u00e3o no android) ou clicar <a href=\"https:\/\/f-droid.org\/F-Droid.apk\">aqui.<\/a><\/li><br><li>Necess\u00e1rio permitir a instala\u00e7\u00e3o de fontes desconhecidas no seu telefone (necess\u00e1rio para qualquer app fora da google playstore.<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"159\" class=\"size-medium wp-image-51 aligncenter\" src=\"http:\/\/192.168.0.52\/wp-content\/uploads\/2024\/09\/1-300x159.jpeg\" alt=\"\" srcset=\"https:\/\/jorgecarneirob.ddns.net\/wp-content\/uploads\/2024\/09\/1-300x159.jpeg 300w, https:\/\/jorgecarneirob.ddns.net\/wp-content\/uploads\/2024\/09\/1.jpeg 630w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/li><\/ol><\/p>\n\n\n\n<p><ol><li>\u00a0<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"294\" class=\"size-medium wp-image-50 aligncenter\" src=\"http:\/\/192.168.0.52\/wp-content\/uploads\/2024\/09\/2-300x294.jpeg\" alt=\"\" srcset=\"https:\/\/jorgecarneirob.ddns.net\/wp-content\/uploads\/2024\/09\/2-300x294.jpeg 300w, https:\/\/jorgecarneirob.ddns.net\/wp-content\/uploads\/2024\/09\/2.jpeg 576w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"157\" class=\"size-medium wp-image-49 aligncenter\" src=\"http:\/\/192.168.0.52\/wp-content\/uploads\/2024\/09\/3-300x157.jpeg\" alt=\"\" srcset=\"https:\/\/jorgecarneirob.ddns.net\/wp-content\/uploads\/2024\/09\/3-300x157.jpeg 300w, https:\/\/jorgecarneirob.ddns.net\/wp-content\/uploads\/2024\/09\/3.jpeg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/li><br><li>Ap\u00f3s a instala\u00e7\u00e3o, basta procurar por seus apps favoritos:<\/li><\/ol><\/p>\n\n\n\n<p><ol><li><img loading=\"lazy\" decoding=\"async\" width=\"146\" height=\"300\" class=\"size-medium wp-image-53 aligncenter\" src=\"http:\/\/192.168.0.52\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-15-at-4.19.19-PM-146x300.jpeg\" alt=\"\" srcset=\"https:\/\/jorgecarneirob.ddns.net\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-15-at-4.19.19-PM-146x300.jpeg 146w, https:\/\/jorgecarneirob.ddns.net\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-15-at-4.19.19-PM-500x1024.jpeg 500w, https:\/\/jorgecarneirob.ddns.net\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-15-at-4.19.19-PM.jpeg 720w\" sizes=\"auto, (max-width: 146px) 100vw, 146px\" \/><\/li>Obrigado por ler at\u00e9 aqui.<\/ol><br><p>Duvidas? Deixe nos coment\u00e1rios.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alternativa OpenSource ao Google PlayStore Como funciona o F-Droid? O F-Droid \u00e9 um reposit\u00f3rio de aplicativos Android de c\u00f3digo aberto. Ele funciona da seguinte forma:Reposit\u00f3rio: O F-Droid mant\u00e9m um reposit\u00f3rio de aplicativos Android que s\u00e3o livres e de c\u00f3digo aberto.Verifica\u00e7\u00e3o: Os aplicativos passam por um processo de verifica\u00e7\u00e3o rigoroso para garantir que sejam seguros e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":55,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[6,7,8,10,9],"class_list":["post-47","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobile","tag-android","tag-f-droid","tag-opensource","tag-playstore","tag-smartphone"],"jetpack_featured_media_url":"https:\/\/jorgecarneirob.ddns.net\/wp-content\/uploads\/2024\/09\/1687436360962.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/posts\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/comments?post=47"}],"version-history":[{"count":4,"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/posts\/47\/revisions"}],"predecessor-version":[{"id":90,"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/posts\/47\/revisions\/90"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/media\/55"}],"wp:attachment":[{"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/media?parent=47"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/categories?post=47"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/tags?post=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}