{"id":220,"date":"2025-07-11T19:25:33","date_gmt":"2025-07-11T22:25:33","guid":{"rendered":"http:\/\/192.168.0.52\/?p=220"},"modified":"2025-07-14T12:19:27","modified_gmt":"2025-07-14T15:19:27","slug":"transforme-um-android-em-servidor-linux","status":"publish","type":"post","link":"https:\/\/jorgecarneirob.ddns.net\/index.php\/2025\/07\/11\/transforme-um-android-em-servidor-linux\/","title":{"rendered":"Transforme um android em servidor linux!"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized wp-duotone-unset-1\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"320\" src=\"http:\/\/192.168.0.52\/wp-content\/uploads\/2025\/07\/image.png\" alt=\"\" class=\"wp-image-222\" style=\"width:523px;height:auto\" srcset=\"https:\/\/jorgecarneirob.ddns.net\/wp-content\/uploads\/2025\/07\/image.png 480w, https:\/\/jorgecarneirob.ddns.net\/wp-content\/uploads\/2025\/07\/image-300x200.png 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<p>Neste tutorial, demonstro como transformar seu dispositivo android velho ou quebrado em um servidor linux.<br>Funciona em qualquer dispositivo android, smartphone, tablet ou TVBox.<\/p>\n\n\n\n<p>Pr\u00e9-requisitos: Termux<\/p>\n\n\n\n<p>Defina um IP fixo para o dispositivo nas configura\u00e7\u00f5es de wi-fi (Opcional mas aconselhavel)<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Instalar o termux: Playstore, F-droid ou diretamente do repositorio github do projeto.<br><br>Caso opte por fazer download pelo github: <a href=\"https:\/\/github.com\/termux\/termux-app\/releases\">https:\/\/github.com\/termux\/termux-app\/releases<\/a><br><br>Se n\u00e3o souber a arquitetura do processador do seu dispositivo escolha a vers\u00e3o universal: <a href=\"https:\/\/github.com\/termux\/termux-app\/releases\/download\/v0.119.0-beta.3\/termux-app_v0.119.0-beta.3+apt-android-7-github-debug_universal.apk\"><code>termux-app_v0.119.0-beta.3+apt-android-7-github-debug_universal.apk<\/code><\/a><br> .<\/li>\n\n\n\n<li>Ap\u00f3s instalar o termux vamos atualizar o sistema:<br><code>apt update; apt upgrade -y<\/code><br>Ir\u00e1 solicitar algumas op\u00e7\u00f5es, por\u00e9m s\u00f3 teclar enter que ser\u00e1 a op\u00e7\u00e3o padr\u00e3o e deve funcionar sem problemas.<br> .<\/li>\n\n\n\n<li>Caso opte por fazer o restante da configura\u00e7\u00e3o via SSH a partide de um PC:<br><code>apt install ssh<\/code><br><br>Crie uma senha para o usu\u00e1rio:<br><code>passwd<\/code><br><br>Descubra o nome do usu\u00e1rio:<br><code>whoami<\/code><br><br>Feito isso, basta acessar o terminal(linux) ou cmd(windows):<br><code>ssh nomedousuario@ipdodispositivo -p 8022<\/code><br> .<\/li>\n\n\n\n<li>Vamos utilizar um rootfs (Sistema de arquivos root do linux dentro do termux):<br><code>apt install proot-distro<\/code><br><br>Instalar o debian usando o proot-distro(pd):<br><code>pd install debian<\/code><br><br>iniciar o debian com o proot-distro:<br><code>pd login debian<\/code><br> .<\/li>\n\n\n\n<li>Ap\u00f3s login no debian pelo proot-distro vamos atualizar o debian:<br><code>apt update; apt upgrade -y<\/code><br><br>Agora vamos instalar as depend\u00eancias necess\u00e1rias:<br><code>apt install dialog sudo apt-utils apache2 php php-gd php-mysql mariadb-server<\/code><br>. <\/li>\n\n\n\n<li>Ap\u00f3s a insta\u00e7\u00e3o das depend\u00eancias, precisamos configurar o apache para uma porta alta pois o android protege portas baixas padr\u00e3o como 22 (ssh), 80 (http) entre outras:<br><code>nano \/etc\/apache2\/ports.conf<\/code><br><br>Dentro do arquivo procure por Listen 80 e altere para 8080.<br><code>Ctrl+X<\/code><br>Confirme a altera\u00e7\u00e3o.<br>  .<\/li>\n\n\n\n<li>Iniciando apache. Como n\u00e3o tem systemd nessa vers\u00e3o de debian vamos iniciar o apache da seguinte forma:<br><code>apachectl start<\/code><br>. <\/li>\n\n\n\n<li>Iniciando e configurando mysql (mariadb-server): Como n\u00e3o tem systemd nessa vers\u00e3o de debian vamos iniciar o mysql da seguinte forma:<br><code>sudo -u mysql mysqld_safe &amp;<\/code><br><br>Fa\u00e7a login no mysql:<br><code>mysql -u root<\/code><br><br>Configure a senha root do banco de dados:<br><code>use mysql;<br>set password for 'root'@'localhost' = password('123456');<br>flush privileges;<br>quit;<br><\/code>  .<\/li>\n\n\n\n<li>Configurando sess\u00e3o persistente:<br>Instale o pacote tmux:<br><code>apt install tmux -y<\/code><br><br>Crie uma nova sess\u00e3o:<br><code>tmux new -s nome_da_sessao<\/code><br><br>Reconectar na sess\u00e3o:<br><code>tmux attach -t nome_da_sessao<\/code><br><br>Finalizar uma sess\u00e3o:<br><code>tmux kill-session -t meus_servicos<\/code><br>.<\/li>\n\n\n\n<li>Pronto, ambiente servidor com webserver e banco de dados configurado!<br>Para instala\u00e7\u00e3o do <a href=\"http:\/\/192.168.0.52\/index.php\/2025\/05\/28\/instalacao-do-nextcloud-debian-12\/\">nextcloud<\/a> ou <a href=\"http:\/\/192.168.0.52\/index.php\/2025\/05\/30\/wordpress-no-debian-12-instalacao-completa-do-zero-ao-site-no-ar\/\">wordpress<\/a> siga os passos que j\u00e1 est\u00e3o no blog.<br><br>Qualquer d\u00favida deixe nos coment\u00e1rios.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Neste tutorial, demonstro como transformar seu dispositivo android velho ou quebrado em um servidor linux.Funciona em qualquer dispositivo android, smartphone, tablet ou TVBox. Pr\u00e9-requisitos: Termux Defina um IP fixo para o dispositivo nas configura\u00e7\u00f5es de wi-fi (Opcional mas aconselhavel)<\/p>\n","protected":false},"author":1,"featured_media":222,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[135,136,142,139,145,140,143,137,144,141,134,138],"class_list":["post-220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","tag-android-em-servidor-linux","tag-celular-servidor-linux","tag-debian-no-android","tag-linux-no-android","tag-nextcloud-android","tag-reaproveitar-android","tag-servidor-caseiro","tag-servidor-linux-android","tag-servidor-web-no-android","tag-tablet-servidor","tag-transformar-android-em-servidor","tag-tvbox-linux"],"jetpack_featured_media_url":"https:\/\/jorgecarneirob.ddns.net\/wp-content\/uploads\/2025\/07\/image.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/posts\/220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/comments?post=220"}],"version-history":[{"count":5,"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/posts\/220\/revisions"}],"predecessor-version":[{"id":227,"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/posts\/220\/revisions\/227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/media\/222"}],"wp:attachment":[{"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/media?parent=220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/categories?post=220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jorgecarneirob.ddns.net\/index.php\/wp-json\/wp\/v2\/tags?post=220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}